{"id":80695,"date":"2026-05-12T20:25:42","date_gmt":"2026-05-13T02:25:42","guid":{"rendered":"https:\/\/elreporterohgo.com\/noticias\/?p=80695"},"modified":"2026-05-12T20:32:00","modified_gmt":"2026-05-13T02:32:00","slug":"todo-el-respaldo-del-gobierno-del-estado-a-cebaderos-del-altiplano","status":"publish","type":"post","link":"https:\/\/elreporterohgo.com\/noticias\/2026\/05\/12\/todo-el-respaldo-del-gobierno-del-estado-a-cebaderos-del-altiplano\/","title":{"rendered":"Todo el respaldo del gobierno del estado a cebaderos del Altiplano"},"content":{"rendered":"<p>Alrededor de 6 mil productores, acuden al encuentro con el gobernador Menchaca, en el marco de las Rutas de la Transformaci\u00f3n<\/p>\n<p>El gobierno de Hidalgo ha destinado m\u00e1s de 242 mdp para fortalecer la obra p\u00fablica en ese municipio<\/p>\n<p>APAN, Hgo. &#8211; En compa\u00f1\u00eda de miles de productoras y productoras del campo, el gobernador de Hidalgo, Julio Menchaca Salazar, encabez\u00f3 las Rutas de la Transformaci\u00f3n en el municipio de Apan, donde recorri\u00f3 los Servicios para el Pueblo, entreg\u00f3 programas sociales y anunci\u00f3 nuevos proyectos de infraestructura en beneficio de la poblaci\u00f3n del Altiplano.<\/p>\n<p>\u201cEl amor y el cari\u00f1o a la tierra es heredado de varias generaciones y lo que tenemos como compromiso, nosotros desde esta administraci\u00f3n, es generar las condiciones para que haya dignidad en todas las actividades, particularmente en el campo\u201d, afirm\u00f3 el mandatario.<\/p>\n<p>En ese sentido, Menchaca Salazar realiz\u00f3 la entrega simb\u00f3lica de apoyos del Programa para Dignificar el Campo Hidalguense, mediante los subcomponentes de ma\u00edz, avena y cebada, en beneficio directo de mil 485 productores de los municipios de Almoloya, Apan, Emiliano Zapata, Tepeapulco, Tlanalapa y Zempoala, con una inversi\u00f3n de 6 millones 973 mil 856 pesos.<\/p>\n<p>\u201cReafirmamos el compromiso de seguir fortaleciendo una de las actividades agr\u00edcolas m\u00e1s importantes para Hidalgo y para M\u00e9xico: la producci\u00f3n de cebada maltera\u201d, enfatiz\u00f3 Napole\u00f3n Gonz\u00e1lez P\u00e9rez, secretario de Agricultura y Desarrollo Rural, al destacar que el estado lidera este ramo con una producci\u00f3n anual superior a las 195 mil toneladas, que representan m\u00e1s de mil 314 millones de pesos en beneficio directo de m\u00e1s de 12 mil 500 personas productoras.<\/p>\n<p>Por lo anterior, Gonz\u00e1lez P\u00e9rez adelant\u00f3 que se fortalecer\u00e1n los esquemas de acompa\u00f1amiento t\u00e9cnico, impulsando mejores condiciones para la comercializaci\u00f3n de la cebada sin intermediarios y generando oportunidades reales, sumado a una inversi\u00f3n de 57 millones de pesos para la entrega de semilla de ma\u00edz, avena y jitomate para m\u00e1s de 8 mil 200 productores.<\/p>\n<p>Al respecto, Candelaria P\u00e9rez, productora de cebada, extern\u00f3 su reconocimiento al gobierno de Hidalgo, as\u00ed como al mandatario estatal, Julio Menchaca, por los diferentes apoyos brindados al campo, que permaneci\u00f3 muchos a\u00f1os en el olvido.<\/p>\n<p>En materia de infraestructura, Menchaca Salazar indic\u00f3 que, en lo que va de la administraci\u00f3n, el municipio de Apan ha recibido una inversi\u00f3n hist\u00f3rica superior a los 242 millones de pesos en 20 obras, entre las que destacan la reconstrucci\u00f3n de la carretera estatal Apan\u2013La Uni\u00f3n, la rehabilitaci\u00f3n de accesos carreteros, pavimentaciones, infraestructura hidr\u00e1ulica, as\u00ed como obras complementarias de energ\u00eda y vivienda.<\/p>\n<p>Para 2026, el titular del gobierno de Hidalgo anunci\u00f3 nuevos proyectos, como el equipamiento electromec\u00e1nico y l\u00ednea de conducci\u00f3n del pozo El Tigre, la construcci\u00f3n de pavimento de concreto hidr\u00e1ulico en el Libramiento Jos\u00e9 Francisco Osorno y la rehabilitaci\u00f3n de la carretera Apan\u2013La Uni\u00f3n, entronque con la calle Jaime Nun\u00f3.<\/p>\n<p>Por su parte, Alejandro S\u00e1nchez Garc\u00eda, secretario de Infraestructura P\u00fablica y Desarrollo Urbano Sostenible, resalt\u00f3 que, desde el inicio de la administraci\u00f3n a la fecha, se han invertido m\u00e1s de 25 mil millones en proyectos de infraestructura en los 84 municipios, lo que representa una cifra sin precedentes en la entidad.<\/p>\n<p>Finalmente, Zorayda Robles Barrera, alcaldesa de Apan, agradeci\u00f3 los apoyos entregados al sector campesino, as\u00ed como los proyectos de infraestructura desarrollados en el municipio, mismos que son un reflejo del amor a la regi\u00f3n del Altiplano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alrededor de 6 mil productores, acuden al encuentro con el gobernador Menchaca, en el marco de las Rutas de la Transformaci\u00f3n El gobierno de Hidalgo ha destinado m\u00e1s de 242 mdp para fortalecer la obra p\u00fablica en ese municipio APAN, Hgo. &#8211; En compa\u00f1\u00eda de miles de productoras y productoras del campo, el gobernador de<\/p>\n","protected":false},"author":2,"featured_media":80696,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,54],"tags":[],"class_list":{"0":"post-80695","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-hidalgo","8":"category-lo-ultimo"},"_links":{"self":[{"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/posts\/80695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/comments?post=80695"}],"version-history":[{"count":2,"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/posts\/80695\/revisions"}],"predecessor-version":[{"id":80698,"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/posts\/80695\/revisions\/80698"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/media\/80696"}],"wp:attachment":[{"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/media?parent=80695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/categories?post=80695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/tags?post=80695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}