{"id":57684,"date":"2023-08-08T01:02:24","date_gmt":"2023-08-08T06:02:24","guid":{"rendered":"https:\/\/elreporterohgo.com\/noticias\/?p=57684"},"modified":"2023-08-08T01:02:25","modified_gmt":"2023-08-08T06:02:25","slug":"recuperan-automoviles-robados-y-devueltos-a-sus-duenos","status":"publish","type":"post","link":"https:\/\/elreporterohgo.com\/noticias\/2023\/08\/08\/recuperan-automoviles-robados-y-devueltos-a-sus-duenos\/","title":{"rendered":"Recuperan autom\u00f3viles robados y devueltos a sus due\u00f1os"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"598\" src=\"https::\/\/elreporterohgo.com\/noticias\/wp-content\/uploads\/2023\/08\/xqgober-2-1024x598.jpg\" alt=\"\" class=\"wp-image-57685\" srcset=\"https:\/\/elreporterohgo.com\/noticias\/wp-content\/uploads\/2023\/08\/xqgober-2-1024x598.jpg 1024w, https:\/\/elreporterohgo.com\/noticias\/wp-content\/uploads\/2023\/08\/xqgober-2-300x175.jpg 300w, https:\/\/elreporterohgo.com\/noticias\/wp-content\/uploads\/2023\/08\/xqgober-2-768x449.jpg 768w, https:\/\/elreporterohgo.com\/noticias\/wp-content\/uploads\/2023\/08\/xqgober-2.jpg 1611w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p> <br>Pachuca de Soto, Hgo. &#8211; Al concluir la reuni\u00f3n del Gabinete de Seguridad, el gobernador de Hidalgo, Julio Menchaca Salazar, dio a conocer que al d\u00eda de hoy se cuenta con el reporte de 3 mil 574 autos robados, de los cuales mil 965 han sido recuperados y mil 451 ya fueron devueltos a las personas propietarias.\u00a0<\/p>\n\n\n\n<p>Respecto a los veh\u00edculos que faltan por ser reclamados, el titular del Ejecutivo estatal explic\u00f3 que estos se encuentran bajo resguardo de la Procuradur\u00eda General de Justicia del Estado de Hidalgo, por lo que las personas afectadas podr\u00e1n ponerse en contacto a trav\u00e9s de la p\u00e1gina de Facebook de la dependencia para conocer los pormenores de su entrega.&nbsp;<\/p>\n\n\n\n<p>\u201cCientos de mujeres y hombres trabajan de manera incansable para garantizar la paz y seguridad de Hidalgo; hoy contamos con instituciones confiables con las que avanzamos a paso decidido a fin de prevenir el delito y asegurar el acceso a la justicia\u201d, resalt\u00f3 el mandatario.&nbsp;<\/p>\n\n\n\n<p>Finalmente, Menchaca Salazar puntualiz\u00f3 que se refuerzan las tareas de coordinaci\u00f3n con instituciones de seguridad para seguir bajando posiciones en el <em>ranking<\/em> nacional de robo de hidrocarburos.&nbsp;<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pachuca de Soto, Hgo. &#8211; Al concluir la reuni\u00f3n del Gabinete de Seguridad, el gobernador de Hidalgo, Julio Menchaca Salazar, dio a conocer que al d\u00eda de hoy se cuenta con el reporte de 3 mil 574 autos robados, de los cuales mil 965 han sido recuperados y mil 451 ya fueron devueltos a las<\/p>\n","protected":false},"author":2,"featured_media":57685,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":{"0":"post-57684","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-hidalgo"},"_links":{"self":[{"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/posts\/57684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/comments?post=57684"}],"version-history":[{"count":1,"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/posts\/57684\/revisions"}],"predecessor-version":[{"id":57686,"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/posts\/57684\/revisions\/57686"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/media\/57685"}],"wp:attachment":[{"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/media?parent=57684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/categories?post=57684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/tags?post=57684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}