{"id":57109,"date":"2023-07-07T22:53:28","date_gmt":"2023-07-08T03:53:28","guid":{"rendered":"https:\/\/elreporterohgo.com\/noticias\/?p=57109"},"modified":"2023-07-07T22:53:29","modified_gmt":"2023-07-08T03:53:29","slug":"%ef%bb%bfcon-altura-de-miras-las-rutas-de-la-transformacion-llegan-al-valle-de-tulancingo","status":"publish","type":"post","link":"https:\/\/elreporterohgo.com\/noticias\/2023\/07\/07\/%ef%bb%bfcon-altura-de-miras-las-rutas-de-la-transformacion-llegan-al-valle-de-tulancingo\/","title":{"rendered":"\ufeffCon altura de miras, las Rutas de la Transformaci\u00f3n llegan al Valle de Tulancingo"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"664\" src=\"https::\/\/elreporterohgo.com\/noticias\/wp-content\/uploads\/2023\/07\/zzxq-2-1024x664.jpg\" alt=\"\" class=\"wp-image-57111\" srcset=\"https:\/\/elreporterohgo.com\/noticias\/wp-content\/uploads\/2023\/07\/zzxq-2-1024x664.jpg 1024w, https:\/\/elreporterohgo.com\/noticias\/wp-content\/uploads\/2023\/07\/zzxq-2-300x194.jpg 300w, https:\/\/elreporterohgo.com\/noticias\/wp-content\/uploads\/2023\/07\/zzxq-2-768x498.jpg 768w, https:\/\/elreporterohgo.com\/noticias\/wp-content\/uploads\/2023\/07\/zzxq-2.jpg 1574w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"974\" height=\"1024\" src=\"https::\/\/elreporterohgo.com\/noticias\/wp-content\/uploads\/2023\/07\/zxtul-2-974x1024.jpg\" alt=\"\" class=\"wp-image-57110\" srcset=\"https:\/\/elreporterohgo.com\/noticias\/wp-content\/uploads\/2023\/07\/zxtul-2-974x1024.jpg 974w, https:\/\/elreporterohgo.com\/noticias\/wp-content\/uploads\/2023\/07\/zxtul-2-285x300.jpg 285w, https:\/\/elreporterohgo.com\/noticias\/wp-content\/uploads\/2023\/07\/zxtul-2-768x808.jpg 768w, https:\/\/elreporterohgo.com\/noticias\/wp-content\/uploads\/2023\/07\/zxtul-2.jpg 1259w\" sizes=\"(max-width: 974px) 100vw, 974px\" \/><\/figure>\n\n\n\n\n\n<ul class=\"wp-block-list\"><li><em>El mandatario estatal asegur\u00f3 que su administraci\u00f3n trabaja para fortalecer la relaci\u00f3n entre los 3 niveles de gobierno<\/em><\/li><\/ul>\n\n\n\n<p>\u201cSe hizo un compromiso desde la campa\u00f1a: convertir a Hidalgo en una potencia de la mano de todas y todos\u201d, asever\u00f3 el gobernador de Hidalgo, Julio Menchaca Salazar durante las Rutas de la Transformaci\u00f3n en Cuautepec y Tulancingo, municipios que recibir\u00e1n m\u00e1s de 180 millones de pesos en obra p\u00fablica y apoyos directos a la econom\u00eda de esta regi\u00f3n de la entidad.<\/p>\n\n\n\n<p>\u201cAntes no sab\u00edamos en qu\u00e9 se gastaban el dinero, hoy transparentamos los procesos para que las obras no sean de adorno y a los pocos meses se encuentren en mal estado. Hoy trabajamos con altura de miras para cuidar por el bien de nuestro estado, pues estoy convencido de que en esa sinergia construimos el Hidalgo que merecemos\u201d, destac\u00f3 durante su intervenci\u00f3n.<\/p>\n\n\n\n<p>En su visita a Tulancingo, Menchaca Salazar anunci\u00f3 el inicio de la construcci\u00f3n del distribuidor vial en el entronque de la carretera federal Tuxpan &#8211; Jaltepec, con un monto de inversi\u00f3n de m\u00e1s de 160 millones de pesos y que representa una promesa cumplida de campa\u00f1a.<\/p>\n\n\n\n<p>Tambi\u00e9n adelant\u00f3 que con m\u00e1s de 5.8 millones de pesos recaudados a trav\u00e9s del programa de reemplacamiento \u201cDale marcha a la transformaci\u00f3n\u201d, se iniciar\u00e1n la pavimentaci\u00f3n hidr\u00e1ulica en la calle Ana Lamache, en el acceso al IMSS, subdelegaci\u00f3n Tulancingo y en el acceso al Cuartel de Seguridad.<\/p>\n\n\n\n<p>Igualmente particip\u00f3 en la entrega de las instalaciones del Centro de Atenci\u00f3n de Seguridad, Video vigilancia, Inteligencia y Monitoreo Policial (C4), el cual tuvo un costo de 23 millones 34 mil pesos; en tanto, que la primera etapa de la pavimentaci\u00f3n hidr\u00e1ulica en la colonia San Francisco Huatengo, necesit\u00f3 de 2 millones 317 mil 700 pesos para su realizaci\u00f3n.<\/p>\n\n\n\n<p>Ah\u00ed el gobernador anunci\u00f3 que se han concluido los trabajos de la construcci\u00f3n del colector de aguas negras y la pavimentaci\u00f3n hidr\u00e1ulica en el camino a Rancho San Francisco, infraestructura municipal con un valor cercano a los 10 millones de pesos.<\/p>\n\n\n\n<p>En Cuautepec de Hinojosa, el titular del Ejecutivo estatal encabez\u00f3 la entrega simb\u00f3lica del programa \u201cTu Experiencia Transforma\u201d, el cual consta de una beca de 6 mil pesos mensuales durante 6 meses a personas adultas mayores que desean continuar trabajando, por lo que reconoci\u00f3 la buena disposici\u00f3n de empresas instaladas en la entidad para abrir sus puertas a este sector poblacional.<\/p>\n\n\n\n<p>Del mismo modo, dio a conocer que a trav\u00e9s del programa de reemplacamiento vehicular, se llevar\u00e1 a cabo la pavimentaci\u00f3n hidr\u00e1ulica en la localidad de El Tepeyac, obra que requerir\u00e1 de una inversi\u00f3n superior a los 2 millones de pesos, mientras que para la pavimentaci\u00f3n hidr\u00e1ulica en la carretera Santa Rita &#8211; Santa Elena Paliseca, se utilizar\u00e1n otros 3.5 millones de pesos del mismo fondo.<\/p>\n\n\n\n<p>Menchaca Salazar explic\u00f3 que para fortalecer las acciones en materia de salud se realizar\u00e1n trabajos de conservaci\u00f3n y mantenimiento del Centro de Salud de Cuautepec, tareas que alcanzan los 723 mil 827 pesos de inversi\u00f3n. Asimismo, se iniciar\u00e1n obras de infraestructura educativa en las localidades de Huayapita y Santa Elena Paliseca, con un monto de inversi\u00f3n de 2 millones 555 mil 260 pesos.<\/p>\n\n\n\n<p>Respecto a las pol\u00edticas de seguridad, el gobernador consider\u00f3 que \u201cdesafortunadamente el robo de combustible no s\u00f3lo representa el robo a la naci\u00f3n, es un riesgo constante para muchas comunidades, por ello trabajamos para garantizar la seguridad de la poblaci\u00f3n y reconozco la participaci\u00f3n de la ciudadan\u00eda al hacer las denuncias correspondientes para inhibir estas conductas\u201d.<\/p>\n\n\n\n<p>Por su parte, el delegado del Programas para el Desarrollo en Hidalgo, Abraham Mendoza Zenteno, agradeci\u00f3 la colaboraci\u00f3n entre la entidad y la federaci\u00f3n, por ello anunci\u00f3 la entrega del componente \u201cBienpesca\u201d, el cual consta de un apoyo de 7 mil 500 pesos a cada pescador, con una inversi\u00f3n superior a los 6 millones de pesos para la entidad.<\/p>\n\n\n\n<p>\u201cLa autosuficiencia alimentaria es uno de los objetivos prioritarios del presidente, Andr\u00e9s Manuel L\u00f3pez Obrador, para que quienes nos dan de comer tengan qu\u00e9 comer. En este programa cada pescador tiene la posibilidad de reclutar a una o un joven entre 18 y 29 a\u00f1os que ser\u00e1 beneficiario del programa \u201cJ\u00f3venes Construyendo el Futuro\u201d.<\/p>\n\n\n\n<p>Alejandro S\u00e1nchez Garc\u00eda, secretario de Infraestructura P\u00fablica y Desarrollo Urbano Sostenible, enfatiz\u00f3 que a 10 meses de administraci\u00f3n ya se pueden ver los primeros resultados: \u201cAnunciamos obras con recursos asegurados, pues con estas obras atendemos las necesidad de cada regi\u00f3n\u201d, subray\u00f3.<\/p>\n\n\n\n<p>El titular de la Secretar\u00eda de Desarrollo Econ\u00f3mico, Carlos Henkel Escorza, explic\u00f3 que el programa \u201cTu experiencia transforma\u201d, representa un ejemplo a nivel nacional pues permitir\u00e1 generar un v\u00ednculo entre el sector privado y personas de la tercera edad: \u201cPara este proyecto se ha dispuesto de un presupuesto de 5 millones de pesos para brindar 132 becas y al d\u00eda de hoy tenemos la mitad de becas otorgadas\u201d.<\/p>\n\n\n\n<p>Zorayda Robles Barrera, secretaria de Salud, resalt\u00f3 que para mejorar la calidad del servicio, esta administraci\u00f3n apuesta por la prevenci\u00f3n y la salud comunitaria. \u201cPrimero es el pueblo y la salud es un derecho humano\u201d, recalc\u00f3.<\/p>\n\n\n\n<p>Finalmente, el subsecretario de Educaci\u00f3n Media Superior y Superior de la Secretar\u00eda de Educaci\u00f3n P\u00fablica, Daniel Fragoso Torres, manifest\u00f3 que la inversi\u00f3n en la educaci\u00f3n representa un paso hacia la consolidaci\u00f3n de la transformaci\u00f3n: \u201cCada peso invertido en equipamiento es una inversi\u00f3n en un futuro brillante para nuestras y nuestros estudiantes. Por ellas, por ellos, por ustedes y por nosotros trabajamos para alcanzar el m\u00e1ximo potencial de nuestro estado\u201d.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mandatario estatal asegur\u00f3 que su administraci\u00f3n trabaja para fortalecer la relaci\u00f3n entre los 3 niveles de gobierno \u201cSe hizo un compromiso desde la campa\u00f1a: convertir a Hidalgo en una potencia de la mano de todas y todos\u201d, asever\u00f3 el gobernador de Hidalgo, Julio Menchaca Salazar durante las Rutas de la Transformaci\u00f3n en Cuautepec y<\/p>\n","protected":false},"author":2,"featured_media":57111,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":{"0":"post-57109","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-hidalgo"},"_links":{"self":[{"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/posts\/57109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/comments?post=57109"}],"version-history":[{"count":1,"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/posts\/57109\/revisions"}],"predecessor-version":[{"id":57112,"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/posts\/57109\/revisions\/57112"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/media\/57111"}],"wp:attachment":[{"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/media?parent=57109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/categories?post=57109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/tags?post=57109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}