{"id":57094,"date":"2023-07-07T10:38:59","date_gmt":"2023-07-07T15:38:59","guid":{"rendered":"https:\/\/elreporterohgo.com\/noticias\/?p=57094"},"modified":"2023-07-07T10:39:00","modified_gmt":"2023-07-07T15:39:00","slug":"gobierno-hidalguense-busca-mejorar-espacios-recreativos","status":"publish","type":"post","link":"https:\/\/elreporterohgo.com\/noticias\/2023\/07\/07\/gobierno-hidalguense-busca-mejorar-espacios-recreativos\/","title":{"rendered":"Gobierno hidalguense busca mejorar espacios recreativos"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img fetchpriority=\"high\" decoding=\"async\" width=\"855\" height=\"472\" src=\"https::\/\/elreporterohgo.com\/noticias\/wp-content\/uploads\/2023\/07\/ZXA1.jpg\" alt=\"\" class=\"wp-image-57095\" srcset=\"https:\/\/elreporterohgo.com\/noticias\/wp-content\/uploads\/2023\/07\/ZXA1.jpg 855w, https:\/\/elreporterohgo.com\/noticias\/wp-content\/uploads\/2023\/07\/ZXA1-300x166.jpg 300w, https:\/\/elreporterohgo.com\/noticias\/wp-content\/uploads\/2023\/07\/ZXA1-768x424.jpg 768w\" sizes=\"(max-width: 855px) 100vw, 855px\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\"><li><em>Creaci\u00f3n de espacios recreativos, culturales y de integraci\u00f3n familiar es uno de los compromisos de esta administraci\u00f3n<\/em><\/li><\/ul>\n\n\n\n<p>El gobierno del estado de Hidalgo, encabezado por Julio Menchaca Salazar, y la Secretar\u00eda de Contralor\u00eda, conducida por \u00c1lvaro Bardales Ram\u00edrez, mantienen un trabajo continuo a favor de un desarrollo sostenible para la entidad.<br><\/p>\n\n\n\n<p>En el Plan Estatal de Desarrollo 2022-2028, en el acuerdo para el desarrollo sostenible e infraestructura transformadora, el mandatario estatal plantea una mejora en los espacios de recreaci\u00f3n, con \u00e9nfasis en el cuidado del medio ambiente y la preservaci\u00f3n de los recursos naturales.&nbsp;<br><\/p>\n\n\n\n<p>Se dio cumplimiento a este acuerdo durante la Tercera Sesi\u00f3n Extraordinaria de adecuaciones presupuestales de la Operadora de Eventos del Estado de Hidalgo, estando presentes el director de dicho organismo, Marco Antonio Aranz\u00e1bal Ju\u00e1rez, as\u00ed como los integrantes de la Junta de Gobierno y el Comisario P\u00fablico, como parte de la Contralor\u00eda.<br><\/p>\n\n\n\n<p>Durante la reuni\u00f3n, se present\u00f3 y aprob\u00f3 la ampliaci\u00f3n l\u00edquida de recursos autorizados por la Secretar\u00eda de Hacienda para la propuesta \u201cDesarrollo del proyecto ejecutivo arquitect\u00f3nico para la remodelaci\u00f3n del Parque David Ben Guri\u00f3n\u201d, que se refiere a la creaci\u00f3n de espacios recreativos, culturales y de integraci\u00f3n familiar en la ciudad de Pachuca de Soto.<br><\/p>\n\n\n\n<p>Cabe destacar que para el gobierno del Estado el bienestar de los hidalguenses es prioridad, por ello toma las medidas necesarias para fortalecer e impulsar una transformaci\u00f3n de la entidad de una manera uniforme, que contemple todos los \u00e1mbitos de desarrollo: personal, profesional, econ\u00f3mico, de salud y social, con lo cual se refrenda el compromiso que tiene con la ciudadan\u00eda.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Creaci\u00f3n de espacios recreativos, culturales y de integraci\u00f3n familiar es uno de los compromisos de esta administraci\u00f3n El gobierno del estado de Hidalgo, encabezado por Julio Menchaca Salazar, y la Secretar\u00eda de Contralor\u00eda, conducida por \u00c1lvaro Bardales Ram\u00edrez, mantienen un trabajo continuo a favor de un desarrollo sostenible para la entidad. En el Plan Estatal<\/p>\n","protected":false},"author":2,"featured_media":57095,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":{"0":"post-57094","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-hidalgo"},"_links":{"self":[{"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/posts\/57094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/comments?post=57094"}],"version-history":[{"count":1,"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/posts\/57094\/revisions"}],"predecessor-version":[{"id":57096,"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/posts\/57094\/revisions\/57096"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/media\/57095"}],"wp:attachment":[{"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/media?parent=57094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/categories?post=57094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elreporterohgo.com\/noticias\/wp-json\/wp\/v2\/tags?post=57094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}